{"id":815,"count":172,"description":"","link":"https:\/\/answear.ua\/blog\/category\/lifestyle","name":"LIFESTYLE","slug":"lifestyle","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/answear.ua\/blog\/wp-json\/wp\/v2\/categories\/815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/answear.ua\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/answear.ua\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/answear.ua\/blog\/wp-json\/wp\/v2\/posts?categories=815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}